{"id":589,"date":"2011-05-25T11:19:05","date_gmt":"2011-05-25T09:19:05","guid":{"rendered":"http:\/\/lettresoubliees1418.fr\/wordpress\/?p=589"},"modified":"2011-05-15T17:23:59","modified_gmt":"2011-05-15T15:23:59","slug":"lettre-du-5-mars-1917-demilie-sibaud","status":"publish","type":"post","link":"https:\/\/lettresoubliees1418.fr\/wordpress\/2011\/05\/lettre-du-5-mars-1917-demilie-sibaud\/","title":{"rendered":"Lettre du 5 mars 1917 d&rsquo;Emilie Sibaud"},"content":{"rendered":"<h4>Vincennes, le 5 mars 1917<br \/>\nLundi matin<\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Mon ch\u00e9ri,<br \/>\n<span style=\"color: #800080;\">Je viens de recevoir ta longue lettre, qui m\u2019a caus\u00e9e une grande joie, elle a \u00e9t\u00e9 un rayon de soleil pour moi, depuis 3 jours j\u2019\u00e9tais anxieuse d\u2019avoir de tes nouvelles.<\/span><br \/>\nPour r\u00e9pondre \u00e0 tes questions, je te dirais que notre mignonne a des cheveux noirs comme petit Yves bien fournis, de toutes petites oreilles, le nez moins long que son fr\u00e8re et le teint tr\u00e8s clair, je crois qu\u2019elle aura les yeux bleus et ton front. Elle a comme Yves le cr\u00e2ne fort. J\u2019ai tout de suite regard\u00e9 ses petites mains, elles sont longues comme celles d\u2019Yves, et chose bizarre elle a d\u00e9j\u00e0 les m\u00eames lignes nettes dessin\u00e9es. Elle a l\u2019int\u00e9rieur de la main plus plat que lui. Pour le corps, elle a la poitrine tr\u00e8s bomb\u00e9e, de tous petits pieds. Maintenant que je te fasse des compliments sur ta fille, elle a dormi toute la nuit de 10h \u00e0 6h \u00bd ; l\u00e0 Yves s\u2019\u00e9tant \u00e9veill\u00e9, elle a un peu boug\u00e9, je l\u2019ai prise croyant qu\u2019elle allait demander la t\u00e9t\u00e9e, elle m\u2019a bien regard\u00e9e et puis elle s\u2019est remise \u00e0 dormir jusqu\u2019\u00e0 8h ; l\u00e0 elle a t\u00e9t\u00e9, puis elle est rest\u00e9e regarder, ensuite on lui a fait sa toilette, elle a de nouveau t\u00e9t\u00e9. <span style=\"color: #800080;\">Mademoiselle sommeille doucement, tandis que je t\u2019\u00e9cris.<\/span> Elle est tr\u00e8s dr\u00f4le quand on me la donne pour t\u00e9ter, elle attend d\u2019abord un peu et puis avec sa petite main elle cherche et apr\u00e8s la bouche, au bout de quelques minutes alors seulement elle pousse des cris. Je t\u2019\u00e9cris tout ces petits d\u00e9tails, car je sais bien qu\u2019ils t\u2019int\u00e9resseront. <span style=\"color: #800080;\">Notre fillette s\u2019appelle Marcelle Suzanne Emilie<\/span>. Les Gallo ont r\u00e9pondu par t\u00e9l\u00e9gramme. Suzanne est tr\u00e8s flatt\u00e9e qu\u2019elle est son nom. Ils n\u2019ont pu encore venir, Ren\u00e9 a une bronchite assez forte, ils doivent venir cette semaine. Comprends-tu seulement mon \u00e9criture ?<br \/>\nM. Huet s\u2019est occup\u00e9 pour la d\u00e9claration et a servi de t\u00e9moin avec M. Barsar, nous n\u2019avons pas mieux, M. Lombard est malade, revient du midi. Les Huet ont \u00e9t\u00e9 tout \u00e0 fait gentils, vendredi matin Mme Huet m\u2019apportent d\u00e9j\u00e0 des fleurs.<br \/>\nComme je crois d\u00e9j\u00e0 te l\u2019avoir dit, j\u2019ai commenc\u00e9 \u00e0 avoir des petites douleurs \u00e0 3h \u00bd, \u00e0 8h \u00bd de plus fortes. Mme Huet est all\u00e9e chercher la doctoresse. Je ne croyais tout de m\u00eame pas qu\u2019\u00e0 10h \u00bd notre fillette serait l\u00e0. J\u2019ai naturellement souffert, mais j\u2019\u00e9tais beaucoup moins fatigu\u00e9e que pour Yves et j\u2019ai tr\u00e8s bien suivi tout ce que l\u2019on a fait \u00e0 la petite. Elle criait et \u00e9tait bien vivante. Je puis te le dire enfin elle n\u2019a pas fait trop souffrir sa maman. C\u2019est bien gentil \u00e0 elle. J\u2019ai \u00e9norm\u00e9ment de lait, je pourrais prendre un \u00ab nourrisson ! \u00bb. Tout va bien, je te dis plut\u00f4t mieux m\u00eame que pour Yves. J\u2019\u00e9crirai un mot au docteur lui disant que cela m\u2019a pris la nuit et qu\u2019il m\u2019a \u00e9t\u00e9 impossible de le faire pr\u00e9venir. La doctoresse a \u00e9t\u00e9 tout \u00e0 fait aimable, elle m\u2019a dit de la rappeler \u00e0 ton bon souvenir ; son fianc\u00e9 est aussi instructeur \u00e0 Angers \u00e0 l\u2019\u00e9cole d\u2019officier de r\u00e9serve du g\u00e9nie, il est capitaine, ing\u00e9nieur dans le civil lui aussi et esp\u00e8re la fin prochaine. Dieu nous entende. Tant et tant de fois l\u2019espoir a \u00e9t\u00e9 d\u00e9\u00e7u.<br \/>\n<span style=\"color: #800080;\">Maman voulait t\u2019\u00e9crire mais j\u2019ai voulu d\u2019\u00e9crire moi-m\u00eame chaque jour que tu vois autant que possible notre vie, que tu saches qu\u2019\u00e0 tout instant ma pens\u00e9e a \u00e9t\u00e9 vers toi et puis cela t\u2019es une preuve que je n\u2019ai pas eu de peur et que je vais tout \u00e0 fait bien, que ni la peur ni les \u00e9motions, que nous avons eu malheureusement, n\u2019auront pas nui \u00e0 notre mignonne.<\/span><br \/>\nIl ne fait pas froid en tout les cas nous avons toujours eu de 18 \u00e0 22 dans la chambre jour et nuit.<br \/>\nJe vais \u00e9crire \u00e0 Clermont pour leur donner quelques d\u00e9tails. J\u2019ai d\u00fb t\u2019\u00e9crire qu\u2019Oncle Emile m\u2019a envoy\u00e9e une d\u00e9p\u00eache enthousiaste aussit\u00f4t re\u00e7u la notre. J\u2019avais envoy\u00e9 en m\u00eame temps que la tienne.<br \/>\nTante marie a envoy\u00e9 des grands bas \u00e0 Yves, ils sont arriv\u00e9s vendredi. Il faut que je la remercie.<br \/>\nIl faut que je mette aussi un mot \u00e0 Devoyod. J\u2019ai re\u00e7u l\u2019argent mercredi, et donc depuis je n\u2019ai pas beaucoup \u00e9cris. Pour ce qui est des autres lettres, j\u2019ai pr\u00e9venue maintenant Mme Codech\u00e8vre, Armelle, les Oudar, Mme Yulles (qui m\u2019avait re\u00e7ue), Mme B. (qui \u00e9tait venu nous voir au mois de f\u00e9vrier). J\u2019ai fait pr\u00e9venir Mme N., A. (sa m\u00e8re), les autres viendront petit \u00e0 petit, tu ne vois personne \u00e0 me dire ? Que je pourrais oublier ?<br \/>\n(Tu sais la petite poup\u00e9e dort toujours) Elle m\u2019a laiss\u00e9e le temps de t\u2019\u00e9crire un peu longuement.<br \/>\n<span style=\"color: #800080;\">Yves a \u00e9t\u00e9 bien content du r\u00f4le de protecteur que tu lui donnes aupr\u00e8s de sa petite s\u0153ur.<\/span> D\u2019ailleurs il l\u2019avait d\u00e9j\u00e0 pris, pas une minute de jalousie, en riant je lui ai demand\u00e9 s\u2019il voulait t\u00e9ter, il m\u2019a r\u00e9pondu \u00ab je suis trop grand. Je ferais bobo \u00e0 maman, dit non je suis trop grand \u00bb (du coup il ne fait plus pipi dans son lit !) et s\u2019endort tout seul, en revanche il a une tendance \u00e0 devenir plus gar\u00e7on, il a fait une de ces parties avec Melle Campergue. Ils courraient dans tout l\u2019appartement, elle raffole d\u2019Yves, \u00ab il est joli ! Il rit si bien ! Il est si franc ! \u00bb<br \/>\nEnfin hier dimanche, il voulait aller se promener avec elle. Il raisonne comme une grande personne et toujours si franc, si clair, bon c\u0153ur, mais toujours \u00e0 rire. Tu le trouverais bien chang\u00e9. Moi aussi mon ch\u00e9ri, j\u2019aurais bien voulu que tu puisses venir mais ce serait une folie dans ces conditions, si seulement tu pouvais faire [\u2026] ces jours-l\u00e0 \u00e0 P\u00e2ques. Mon oncle dirait que tu y aurais droit. <span style=\"color: #800080;\">Au revoir mon aim\u00e9, que ne puis-je t\u2019embrasser r\u00e9ellement que cela me serait doux de t\u2019avoir pr\u00e8s de moi.<\/span> Je te quitte en t\u2019envoyant de bons baisers. Yves et Marcelle de donnent leurs plus tendres caresses.<\/p>\n<p style=\"text-align: justify;\">Tout \u00e0 toi.<br \/>\nEmilie<\/p>\n<br \/><g:plusone size=\"\" href=\"https%3A%2F%2Flettresoubliees1418.fr%2Fwordpress%2F2011%2F05%2Flettre-du-5-mars-1917-demilie-sibaud%2F\"><\/g:plusone>","protected":false},"excerpt":{"rendered":"<p>Vincennes, le 5 mars 1917 Lundi matin &nbsp; Mon ch\u00e9ri, Je viens de recevoir ta longue lettre, qui m\u2019a caus\u00e9e une grande joie, elle a \u00e9t\u00e9 un rayon de soleil pour moi, depuis 3 jours j\u2019\u00e9tais anxieuse d\u2019avoir de tes &hellip; <a href=\"https:\/\/lettresoubliees1418.fr\/wordpress\/2011\/05\/lettre-du-5-mars-1917-demilie-sibaud\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[17,27,19,41,29,139,28],"_links":{"self":[{"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/posts\/589"}],"collection":[{"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=589"}],"version-history":[{"count":3,"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/posts\/589\/revisions"}],"predecessor-version":[{"id":591,"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/posts\/589\/revisions\/591"}],"wp:attachment":[{"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lettresoubliees1418.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}